{"id":142462,"date":"2020-10-01T07:00:41","date_gmt":"2020-10-01T05:00:41","guid":{"rendered":"https:\/\/rightlivelihood.org\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/"},"modified":"2025-08-20T21:49:27","modified_gmt":"2025-08-20T19:49:27","slug":"belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award","status":"publish","type":"post","link":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/","title":{"rendered":"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020"},"content":{"rendered":"<p><strong>El activista bielorruso a favor de la democracia, Ales Bialiatski, y la organizaci\u00f3n no gubernamental Centro de Derechos Humanos \u201cViasna\u201d recibir\u00e1n conjuntamente el Right Livelihood Award 2020, ampliamente conocido como \u201cPremio Nobel Alternativo\u201d, por su papel en la lucha por la democracia y los derechos humanos en Bielorrusia.<\/strong><\/p>\n<p>Los nombres de las cuatro personas laureadas con el\u00a0<a href=\"https:\/\/www.rightlivelihoodaward.org\/\"><u>Premio Right Livelihood 2020<\/u><\/a>\u00a0se dieron a conocer este jueves en una conferencia de prensa desde la Casa de la Cultura de Estocolmo. El Premio Right Livelihood es un galard\u00f3n de renombre internacional que desde el a\u00f1o 1980 rinde homenaje a valientes agentes de cambio de todo el mundo. Al reconocer acciones valerosas y visionarias y construir poderosas redes globales, el premio tiene como objetivo impulsar un cambio social urgente y duradero.<\/p>\n<p><a href=\"https:\/\/www.rightlivelihoodaward.org\/announcement\/ales-bialiatski-viasna\/l1-es\/\"><u>Ales Bialiatski<\/u><\/a>\u00a0es un activista de derechos humanos de Bielorrusia que lleva casi 30 a\u00f1os liderando una campa\u00f1a por la democracia y la libertad. En 1996 fund\u00f3 el Centro de Derechos Humanos \u201cViasna\u201d, en Minsk, para dar apoyo a personas encarceladas por motivos pol\u00edticos. Desde entonces, Viasna se ha convertido en la principal organizaci\u00f3n no gubernamental que contribuye al desarrollo de la sociedad civil en Bielorrusia, documentando los abusos contra los derechos humanos y supervisando las elecciones.<\/p>\n<p>Ales Bialiatski y Viasna recibir\u00e1n la distinci\u00f3n \u201cpor su determinaci\u00f3n en la lucha por la consecuci\u00f3n de la democracia y los derechos humanos en Bielorrusia\u201d. Es la primera vez que este galard\u00f3n reconoce a alguien de Bierlorrusia.<\/p>\n<p>\u201cRecibir el prestigioso Premio Right Livelihood conlleva una responsabilidad adicional\u201d, afirm\u00f3 Bialiatski. \u201cSoy muy consciente de que se ha dado una combinaci\u00f3n hist\u00f3rica de circunstancias, como la lucha tr\u00e1gica, y al mismo tiempo maravillosa, de mi pueblo por la justicia, sus sacrificios y su generosidad, que han hecho que el trabajo por los derechos humanos en Bielorrusia este a\u00f1o sea m\u00e1s necesario e importante que nunca. Este galard\u00f3n es un s\u00edmbolo de apoyo moral para todos los ciudadanos y ciudadanas de Bielorrusia que persiguen un cambio democr\u00e1tico. Espero que la atenci\u00f3n internacional que atraiga este premio contribuya a hacer el trabajo del Centro de Derechos Humanos Viasna en Bielorrusia m\u00e1s importante y menos peligroso\u201d.<\/p>\n<p>Ole von Uexkull, Director Ejecutivo de la Fundaci\u00f3n Right Livelihood, coment\u00f3: \u201cAles Bialiatski es un destacado activista de derechos humanos que ha jugado un papel fundamental en la lucha por la democracia en Bielorrusia durante las \u00faltimas tres d\u00e9cadas. Bialiatski y Viasna reciben el Premio Right Livelihood en un momento clave de las protestas por el futuro del pa\u00eds. Mientras ciudadanos y ciudadanas de todas condiciones siguen tomando las calles diariamente para manifestarse contra el r\u00e9gimen dictatorial del presidente Lukashenko, este reconocimiento a Bialiatski y Viasna es tambi\u00e9n un s\u00edmbolo de solidaridad internacional con todas aquellas personas que pugnan por la libertad y la democracia en Bielorrusia\u201d.<\/p>\n<p>El\u00a0<u><\/u>de la Fundaci\u00f3n Right Livelihood tambi\u00e9n seleccion\u00f3 a la abogada de derechos humanos y activista iran\u00ed actualmente encarcelada,\u00a0<a href=\"https:\/\/www.rightlivelihoodaward.org\/announcement\/nasrin-sotoudeh\/l3-es\/\"><u>Nasrin Sotoudeh<\/u><\/a>; al abogado estadounidense por los derechos civiles\u00a0<a href=\"https:\/\/www.rightlivelihoodaward.org\/announcement\/bryan-stevenson\/l4-es\/\"><u>Bryan Stevenson<\/u><\/a>, y a la activista y abogada nicarag\u00fcense por los derechos ind\u00edgenas y el ambiente,\u00a0<a href=\"https:\/\/www.rightlivelihoodaward.org\/announcement\/lottie-cunningham-wren\/l2-es\/\"><u>Lottie Cunningham Wren<\/u><\/a>.<\/p>\n<p>Cada galard\u00f3n es acompa\u00f1ado de un mill\u00f3n de coronas suecas (equivalentes a unos 94.000 euros), dinero destinado a apoyar la continuidad del trabajo de las personas laureadas. Como en a\u00f1os anteriores, la selecci\u00f3n de los premios sigui\u00f3 a un proceso abierto de nominaci\u00f3n en el que cualquier persona pod\u00eda presentar personas u organizaciones para ser consideradas al premio. Este a\u00f1o se tuvieron en cuenta 182 nominaciones provenientes de 71 pa\u00edses.<\/p>\n<p>La presentaci\u00f3n del Premio Right Livelihood 2020 se realizar\u00e1 de modo virtual el 3 de diciembre.<\/p>\n<h4><strong>Qui\u00e9nes son\u00a0<\/strong><strong>Ales Bialiatski y el Centro de Derechos Humanos \u201cViasna\u201d<\/strong><\/h4>\n<p>Bajo el r\u00e9gimen del presidente Alexander Lukashenko, Bielorrusia es considerada a menudo como \u201cla \u00faltima dictadura de Europa\u201d. Esta reputaci\u00f3n proviene directamente de su gobierno autoritario en el que las elecciones son fraudulentas y las voces de la oposici\u00f3n, silenciadas. La sociedad civil sufre graves restricciones impuestas por las instituciones estatales que, en la pr\u00e1ctica, son la continuaci\u00f3n del pasado sovi\u00e9tico del pa\u00eds, \u00fanico del continente en el que la pena de muerte sigue en vigor.<\/p>\n<p>Desde mediados de los a\u00f1os 80, Bialiatski lidera una campa\u00f1a no violenta y apartidista para garantizar que se establezcan libertades democr\u00e1ticas y una sociedad civil vibrante en Bielorrusia. Como parte de este trabajo, Bialiatski ha luchado para erradicar la pena de muerte. Como miembro activo del movimiento nacional por los derechos humanos, Bialiatski ha sido arrestado y ha pasado varios a\u00f1os en la c\u00e1rcel, acusado de cargos falsos en un intento de las autoridades bielorrusas de obstaculizar su trabajo. En varias ocasiones, el gobierno tambi\u00e9n ha puesto en su punto de mira a Viasna y a sus miembros.<\/p>\n<p>Pese a todo, los persistentes esfuerzos que Bialiatski y Viasna han realizado a lo largo de su historia para empoderar al pueblo bielorruso y garantizar sus derechos democr\u00e1ticos les han dotado de una fuerza imparable por la libertad. Durante las protestas a favor de la democracia, como las manifestaciones masivas que siguieron a las fraudulentas elecciones presidenciales de 2020, Viasna ha desempe\u00f1ado un papel fundamental abogando por la libertad de reuni\u00f3n, defendiendo los derechos de las personas arrestadas por protestar y documentando las violaciones de derechos humanos. Bialiatski tambi\u00e9n es miembro del Consejo de Coordinaci\u00f3n, creado en agosto de 2020 por la oposici\u00f3n junto con miembros de la sociedad civil con el objetivo de facilitar la transferencia pac\u00edfica de poder en el pa\u00eds.<\/p>\n<p>Asumiendo enormes riesgos personales, Bialiatski y Viasna siguen alz\u00e1ndose a favor de la multitud de personas valientes que protestan contra el r\u00e9gimen dictatorial de Lukashenko. Mediante su compromiso con la democracia y la libertad, Bialiatski y Viasna han sentado las bases para la existencia de una sociedad pac\u00edfica y democr\u00e1tica en Bielorrusia.<\/p>\n<p><strong>Informaci\u00f3n Biogr\u00e1fica<\/strong><br \/>\nLugar de nacimiento: Carelia, Rusia<br \/>\nFecha de nacimiento: 25 de septiembre de 1962<br \/>\nFormaci\u00f3n: Licenciado en 1984 por la Facultad de Historia y Filolog\u00eda de la Universidad Estatal de G\u00f3mel. En 1989 obtuvo su doctorado en el Instituto de Literatura de la Academia de Ciencias de Minsk.<\/p>\n<p>Centro de Derechos Humanos \u201cViasna\u201d, establecido en 1996 con sede en Minsk y oficinas regionales en la mayor\u00eda de las ciudades de Bielorrusia.<\/p>\n<h4><strong>Contactos de prensa<\/strong><\/h4>\n<p>Para entrevistas con representantes de la Fundaci\u00f3n y\/o premiadas\/os:<\/p>\n<p>Espa\u00f1ol: Nayla Azzinnari, +54 9 11 5460 9860,\u00a0<a href=\"mailto:nayla@rightlivelihood.org\"><u>nayla@rightlivelihood.org<\/u><\/a><\/p>\n<p>Ingl\u00e9s: Emoke Bebiak, +41 (0) 783338484,\u00a0<a href=\"mailto:emoke.bebiak@rightlivelihood.org\"><u>emoke.bebiak@rightlivelihood.org<\/u><\/a><\/p>\n<p>Alem\u00e1n: Nina Tesenfitz, +49 (0)170 5763 663,\u00a0<a href=\"mailto:presse@rightlivelihood.org\"><u>presse@rightlivelihood.org<\/u><\/a><\/p>\n<p>Sueco: Johannes Mosskin, +46 (0)704371148,\u00a0<a href=\"mailto:johannes@rightlivelihood.org\"><u>johannes@rightlivelihood.org<\/u><\/a><\/p>\n<ul>\n<li>M\u00e1s informaci\u00f3n\u00a0<a href=\"https:\/\/www.rightlivelihoodaward.org\/2020-announcement\/\"><u>aqu\u00ed<\/u><\/a><\/li>\n<li>Fotograf\u00edas y videos en alta resoluci\u00f3n\u00a0<a href=\"https:\/\/rightlivelihood.resourcespace.com\/pages\/search.php?search=%21collection449&amp;k=7cefd7ee31\"><u>aqu\u00ed<\/u><\/a><\/li>\n<\/ul>\n<h4><\/h4>\n<h4><strong>Acerca del Premio Right Livelihood<\/strong><\/h4>\n<p>Creado en 1980, el Premio Right Livelihood se propone fomentar el coraje humano necesario para lograr la paz, la justicia y la sustentabilidad para todos y todas. Al reconocer las acciones de personas valientes y visionarias y construir poderosas redes en todo el mundo, el premio tiene como objetivo impulsar un cambio social urgente y duradero.<\/p>\n<p>La Fundaci\u00f3n Right Livelihood, con sede en Estocolmo, considera que su rol es ser meg\u00e1fono y escudo de las y los galardonados, proporcion\u00e1ndoles apoyo a largo plazo. Los principales objetivos de la Fundaci\u00f3n son elevar el perfil de las y los premiados y sus acciones, brindar protecci\u00f3n cuando su vida y libertad est\u00e1n en peligro y educar sobre las soluciones innovadoras presentadas por ellos\/as. La Fundaci\u00f3n tiene estatus consultivo especial ante el Consejo Econ\u00f3mico y Social de la ONU.<\/p>\n<p>Una caracter\u00edstica particular del galard\u00f3n es que cualquier persona puede<a href=\"https:\/\/www.rightlivelihoodaward.org\/app\/uploads\/2019\/01\/Guidelines-for-Proposals-2019-ES.pdf\"><u>\u00a0presentar nominaciones<\/u><\/a>\u00a0al Premio Right Livelihood. Las y los laureados son seleccionados por un<a href=\"https:\/\/www.rightlivelihoodaward.org\/honour\/nominate\/jury\/\">\u00a0jurado internacional<\/a>\u00a0despu\u00e9s de un minucioso an\u00e1lisis por parte del equipo de investigaci\u00f3n de la Fundaci\u00f3n. A diferencia de otras distinciones internacionales, el Premio Right Livelihood no tiene categor\u00edas. Reconoce que, para hacer frente a los retos del mundo actual, los trabajos m\u00e1s notables e inspiradores a menudo desaf\u00edan cualquier clasificaci\u00f3n preestablecida.<\/p>\n<p>Hasta la fecha, han recibido este reconocimiento<a href=\"https:\/\/www.rightlivelihoodaward.org\/laureates\/\"><u>\u00a0182 personas y organizaciones procedentes de 72 pa\u00edses<\/u><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El activista bielorruso a favor de la democracia, Ales Bialiatski, y la organizaci\u00f3n no gubernamental Centro de Derechos Humanos \u201cViasna\u201d recibir\u00e1n conjuntamente el Right Livelihood Award 2020, ampliamente conocido como \u201cPremio Nobel Alternativo\u201d, por su papel en la lucha por la democracia y los derechos humanos en Bielorrusia. Los nombres de las cuatro personas laureadas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":115031,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[445,418],"tags":[],"location":[65],"news-type":[386],"topic":[66,59],"the-year":[272],"class_list":["post-142462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ales-bialiatski-viasna-es","category-laureates-es","location-europe","news-type-press-releases","topic-democracy","topic-human-rights","the-year-272"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020 - Right Livelihood<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020 - Right Livelihood\" \/>\n<meta property=\"og:description\" content=\"El activista bielorruso a favor de la democracia, Ales Bialiatski, y la organizaci\u00f3n no gubernamental Centro de Derechos Humanos \u201cViasna\u201d recibir\u00e1n conjuntamente el Right Livelihood Award 2020, ampliamente conocido como \u201cPremio Nobel Alternativo\u201d, por su papel en la lucha por la democracia y los derechos humanos en Bielorrusia. Los nombres de las cuatro personas laureadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/\" \/>\n<meta property=\"og:site_name\" content=\"Right Livelihood\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rightlivelihood\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-01T05:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-20T19:49:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/07\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Right Livelihood Award Communications\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rightlivelihood\" \/>\n<meta name=\"twitter:site\" content=\"@rightlivelihood\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/\"},\"author\":{\"name\":\"Right Livelihood Award Communications\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#\\\/schema\\\/person\\\/4160847f19f839683b577bdce1ad7327\"},\"headline\":\"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020\",\"datePublished\":\"2020-10-01T05:00:41+00:00\",\"dateModified\":\"2025-08-20T19:49:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/\"},\"wordCount\":1403,\"publisher\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rightlivelihood.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg\",\"articleSection\":[\"Ales Bialiatski Viasna\",\"Laureates\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/\",\"url\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/\",\"name\":\"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020 - Right Livelihood\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rightlivelihood.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg\",\"datePublished\":\"2020-10-01T05:00:41+00:00\",\"dateModified\":\"2025-08-20T19:49:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rightlivelihood.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/rightlivelihood.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/news\\\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rightlivelihood.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/\",\"name\":\"Right Livelihood\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#organization\",\"name\":\"Right Livelihood\",\"url\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rightlivelihood.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/rlh-logo-2-1.svg\",\"contentUrl\":\"https:\\\/\\\/rightlivelihood.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/rlh-logo-2-1.svg\",\"caption\":\"Right Livelihood\"},\"image\":{\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rightlivelihood\",\"https:\\\/\\\/x.com\\\/rightlivelihood\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rightlivelihood.org\\\/es\\\/#\\\/schema\\\/person\\\/4160847f19f839683b577bdce1ad7327\",\"name\":\"Right Livelihood Award Communications\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8bf4cb178c89ac02fb7b0edd039ea746db67c2c42069bf40a2e863c6b2321af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8bf4cb178c89ac02fb7b0edd039ea746db67c2c42069bf40a2e863c6b2321af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c8bf4cb178c89ac02fb7b0edd039ea746db67c2c42069bf40a2e863c6b2321af?s=96&d=mm&r=g\",\"caption\":\"Right Livelihood Award Communications\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020 - Right Livelihood","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/","og_locale":"es_ES","og_type":"article","og_title":"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020 - Right Livelihood","og_description":"El activista bielorruso a favor de la democracia, Ales Bialiatski, y la organizaci\u00f3n no gubernamental Centro de Derechos Humanos \u201cViasna\u201d recibir\u00e1n conjuntamente el Right Livelihood Award 2020, ampliamente conocido como \u201cPremio Nobel Alternativo\u201d, por su papel en la lucha por la democracia y los derechos humanos en Bielorrusia. Los nombres de las cuatro personas laureadas [&hellip;]","og_url":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/","og_site_name":"Right Livelihood","article_publisher":"https:\/\/www.facebook.com\/rightlivelihood","article_published_time":"2020-10-01T05:00:41+00:00","article_modified_time":"2025-08-20T19:49:27+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/07\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg","type":"image\/jpeg"}],"author":"Right Livelihood Award Communications","twitter_card":"summary_large_image","twitter_creator":"@rightlivelihood","twitter_site":"@rightlivelihood","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/#article","isPartOf":{"@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/"},"author":{"name":"Right Livelihood Award Communications","@id":"https:\/\/rightlivelihood.org\/es\/#\/schema\/person\/4160847f19f839683b577bdce1ad7327"},"headline":"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020","datePublished":"2020-10-01T05:00:41+00:00","dateModified":"2025-08-20T19:49:27+00:00","mainEntityOfPage":{"@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/"},"wordCount":1403,"publisher":{"@id":"https:\/\/rightlivelihood.org\/es\/#organization"},"image":{"@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/#primaryimage"},"thumbnailUrl":"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/07\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg","articleSection":["Ales Bialiatski Viasna","Laureates"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/","url":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/","name":"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020 - Right Livelihood","isPartOf":{"@id":"https:\/\/rightlivelihood.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/#primaryimage"},"image":{"@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/#primaryimage"},"thumbnailUrl":"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/07\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg","datePublished":"2020-10-01T05:00:41+00:00","dateModified":"2025-08-20T19:49:27+00:00","breadcrumb":{"@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/#primaryimage","url":"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/07\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg","contentUrl":"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/07\/RS10191_RightLivelihood_20201202_007-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/rightlivelihood.org\/es\/news\/belarusian-pro-democracy-activist-ales-bialiatski-receives-2020-right-livelihood-award\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rightlivelihood.org\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/rightlivelihood.org\/es\/\/news\/"},{"@type":"ListItem","position":3,"name":"El activista pol\u00edtico bielorruso Ales Bialiatski recibe el Premio Right Livelihood 2020"}]},{"@type":"WebSite","@id":"https:\/\/rightlivelihood.org\/es\/#website","url":"https:\/\/rightlivelihood.org\/es\/","name":"Right Livelihood","description":"","publisher":{"@id":"https:\/\/rightlivelihood.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rightlivelihood.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rightlivelihood.org\/es\/#organization","name":"Right Livelihood","url":"https:\/\/rightlivelihood.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rightlivelihood.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/09\/rlh-logo-2-1.svg","contentUrl":"https:\/\/rightlivelihood.org\/wp-content\/uploads\/2024\/09\/rlh-logo-2-1.svg","caption":"Right Livelihood"},"image":{"@id":"https:\/\/rightlivelihood.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rightlivelihood","https:\/\/x.com\/rightlivelihood"]},{"@type":"Person","@id":"https:\/\/rightlivelihood.org\/es\/#\/schema\/person\/4160847f19f839683b577bdce1ad7327","name":"Right Livelihood Award Communications","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c8bf4cb178c89ac02fb7b0edd039ea746db67c2c42069bf40a2e863c6b2321af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c8bf4cb178c89ac02fb7b0edd039ea746db67c2c42069bf40a2e863c6b2321af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c8bf4cb178c89ac02fb7b0edd039ea746db67c2c42069bf40a2e863c6b2321af?s=96&d=mm&r=g","caption":"Right Livelihood Award Communications"}}]}},"_links":{"self":[{"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/posts\/142462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/comments?post=142462"}],"version-history":[{"count":2,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/posts\/142462\/revisions"}],"predecessor-version":[{"id":142472,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/posts\/142462\/revisions\/142472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/media\/115031"}],"wp:attachment":[{"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/media?parent=142462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/categories?post=142462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/tags?post=142462"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/location?post=142462"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/news-type?post=142462"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/topic?post=142462"},{"taxonomy":"the-year","embeddable":true,"href":"https:\/\/rightlivelihood.org\/es\/wp-json\/wp\/v2\/the-year?post=142462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}